{"id":3489,"date":"2015-07-05T19:00:57","date_gmt":"2015-07-05T11:00:57","guid":{"rendered":"http:\/\/www.mos-motor.com\/%e8%bf%91%e6%b3%81%e3%83%a1%e3%83%83%e3%82%bb%e3%83%bc%e3%82%b8\/%e6%b4%bb%e5%8b%95%e8%b3%87%e8%a8%8a\/"},"modified":"2017-03-20T11:27:49","modified_gmt":"2017-03-20T03:27:49","slug":"facebook%e3%82%a4%e3%83%99%e3%83%b3%e3%83%88","status":"publish","type":"page","link":"https:\/\/www.mos-motor.com\/ja\/%e8%bf%91%e6%b3%81%e3%83%a1%e3%83%83%e3%82%bb%e3%83%bc%e3%82%b8\/facebook%e3%82%a4%e3%83%99%e3%83%b3%e3%83%88\/","title":{"rendered":"Facebook\u30a4\u30d9\u30f3\u30c8"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_section  avia-builder-el-first   container_wrap sidebar_right'  >\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_slideshow_full-a457438046ccaedb5475bd089590c562\">\n#top #wrap_all .avia-slideshow .av-slideshow-caption.av-av_slideshow_full-a457438046ccaedb5475bd089590c562__0 .avia-caption-title{\nfont-size:40px;\n}\n#top .avia-slideshow .av-slideshow-caption.av-av_slideshow_full-a457438046ccaedb5475bd089590c562__0 .avia-caption-content{\nfont-size:16px;\n}\n#top .avia-slideshow .av-slideshow-caption.av-av_slideshow_full-a457438046ccaedb5475bd089590c562__0 .avia-caption-content p{\nfont-size:16px;\n}\n<\/style>\n<div  class='avia-slideshow av-av_slideshow_full-a457438046ccaedb5475bd089590c562 avia-slideshow-featured av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 28.666666666667%;'><li  class='avia-slideshow-slide av-av_slideshow_full-a457438046ccaedb5475bd089590c562__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-7384 avia-img-lazy-loading-not-7384\"  src=\"https:\/\/www.mos-motor.com\/wp-content\/uploads\/2015\/04\/006m-1500x430.jpg\" width=\"1500\" height=\"430\" title='006(m)' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><div class='av-slideshow-caption av-av_slideshow_full-a457438046ccaedb5475bd089590c562__0 caption_fullwidth caption_right caption_right_framed caption_framed'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >\u30a4\u30d9\u30f3\u30c8\u60c5\u5831<\/h2><div class='avia-caption-content '  itemprop=\"description\" ><p>\u304a\u53cb\u9054\u3078MOS\u3092\u7d39\u4ecb\u3057\u307e\u3057\u3087\u3046\uff01<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<div id='1'  class='avia-section av-av_section-90fdee42b87e166a32d69b6ff1d1d309 main_color avia-section-large avia-no-shadow  avia-builder-el-1  el_after_av_slideshow_full  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-3489'><div class='entry-content-wrapper clearfix'>\n\n\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-3489'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3462,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/pages\/3489"}],"collection":[{"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":5,"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/pages\/3489\/revisions"}],"predecessor-version":[{"id":48706,"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/pages\/3489\/revisions\/48706"}],"up":[{"embeddable":true,"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/pages\/3462"}],"wp:attachment":[{"href":"https:\/\/www.mos-motor.com\/ja\/wp-json\/wp\/v2\/media?parent=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}